{"id":373373,"date":"2025-06-05T12:35:23","date_gmt":"2025-06-05T15:35:23","guid":{"rendered":"https:\/\/redfasta.edu.ar\/?post_type=noticias&#038;p=373373"},"modified":"2025-06-09T08:41:50","modified_gmt":"2025-06-09T11:41:50","slug":"primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red","status":"publish","type":"noticias","link":"https:\/\/redfasta.edu.ar\/fr\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/","title":{"rendered":"Primera reuni\u00f3n del equipo actualizado de la Direcci\u00f3n General de la Red"},"content":{"rendered":"\n<p>Los d\u00edas jueves 29 y viernes 30 de Mayo se desarroll\u00f3 en la ciudad de Mar del Plata la primera reuni\u00f3n del equipo de la Direcci\u00f3n General, que a la luz de la nueva estructura definida por la Presidencia de Fasta, debe velar por el gobierno de la Red Educativa<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"341\" src=\"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre-1024x341.jpg\" alt=\"\" class=\"wp-image-373374\" srcset=\"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre-1024x341.jpg 1024w, https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre-300x100.jpg 300w, https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre-768x256.jpg 768w, https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mayor especificidad para una mayor calidad&nbsp;<\/strong><\/h2>\n\n\n\n<p>Conducidos por el lic. Juan Manuel del Valle Ricci, Director General y por el Dr. Diego Cocchis, Director Asociado, se abocaron al trabajo de renovaci\u00f3n del m\u00e9todo de gesti\u00f3n de los colegios Fasta en pos de responder a la multiplicidad de requerimientos, necesidades y posibilidades, que fruto del crecimiento alcanzado presenta la Red Educativa Fasta.<\/p>\n\n\n\n<p>Participaron de las jornadas de trabajo junto a los directores de la Red, los referentes de las diferentes \u00e1reas y programas: lic. Yanina Reinoso, Abg. Dafne Montoya, el lic. Santiago Roveda y lic. Marcelo Varela; tambi\u00e9n la lic. Josefina Torres, secretar\u00eda de la direcci\u00f3n y en modo virtual el Pbro. Daniel Torres Cox, asesor Vicario de la Red.\u00a0<\/p>\n\n\n\n<p>Para los dos d\u00edas de jornada la agenda incluy\u00f3 la presentaci\u00f3n de los objetivos de la Direcci\u00f3n, los lineamientos generales y las principales \u00e1reas de trabajo. Un informe exhaustivo sobre el estado de situaci\u00f3n de los colegios de la Red fue el documento central. Los momentos de reflexi\u00f3n permitieron a los miembros del equipo asumir la tarea desde una esp\u00edritu de misi\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"341\" src=\"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre1-1024x341.jpg\" alt=\"\" class=\"wp-image-373382\" srcset=\"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre1-1024x341.jpg 1024w, https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre1-300x100.jpg 300w, https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre1-768x256.jpg 768w, https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/equipo-dgre1.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Gesti\u00f3n integrada e integradora&nbsp;<\/strong><\/h2>\n\n\n\n<p>Uno de los mayores desaf\u00edos del equipo de la Direcci\u00f3n General de la Red ser\u00e1 la de optimizar el trabajo integrado de todas las \u00e1reas de la Presidencia que gestionan alg\u00fan \u00e1mbito de la realidad de las obras educativas. Muchas son las aristas que intervienen en la gesti\u00f3n de una red tan grande y diversa, lo comunitario y de personal, lo pedag\u00f3gico, lo pastoral, lo comunicacional, lo administrativo y lo jur\u00eddico. \u00a0Coordinar una estrategia com\u00fan a todos representa siempre un comprometido\u00a0trabajo coordinar en una estrategia com\u00fan a todos, m\u00e1s cuando el crecimiento desborda los odres.\u00a0\u00a0<\/p>\n\n\n\n<p>En este sentido la reuni\u00f3n de la Direcci\u00f3n General de la Red cont\u00f3 con la participaci\u00f3n de la Direcci\u00f3n de Comunicaciones, con quienes trabaj\u00f3 en cuestiones de competitividad, mejora de procesos, de v\u00ednculos y experiencias de los p\u00fablicos.<\/p>\n\n\n\n<p>En el \u00e1mbito de la planificaci\u00f3n estrat\u00e9gica, se trabaj\u00f3 en una vasta agenda que contempla diversas instancias como encuentros con el directorio y formaci\u00f3n con Apoderados Legales.<\/p>\n\n\n\n<p>Al final del encuentro, la reflexi\u00f3n en torno a la pregunta &#8220;Tenemos un denario, \u00bfen qu\u00e9 lo disponemos?&#8221; invit\u00f3 a pensar sobre la gesti\u00f3n de los recursos y la sustentabilidad.<\/p>\n\n\n\n<p>Importante encuentro para consolidar la estructura y la hoja de ruta de la Direcci\u00f3n General de la Red, siendo fieles a los valores que definen el estilo propio y sentando las bases para una etapa de renovaci\u00f3n y actualizaci\u00f3n.\u00a0<br><\/p>\n","protected":false},"author":2,"featured_media":373377,"template":"","tipo":[55],"categoria":[41],"fuente":[],"origen":[78],"class_list":["post-373373","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","tipo-con-imagen","origen-propia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.1 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Primera reuni\u00f3n del equipo actualizado de la Direcci\u00f3n General de la Red<\/title>\n<meta name=\"description\" content=\"Equipo actualizado de la Direcci\u00f3n General de la Red Educativa Fasta se re\u00fane. Mayor especificidad para una mayor calidad. Gesti\u00f3n integradora\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primera reuni\u00f3n del equipo actualizado de la Direcci\u00f3n General de la Red\" \/>\n<meta property=\"og:description\" content=\"Equipo actualizado de la Direcci\u00f3n General de la Red Educativa Fasta se re\u00fane. Mayor especificidad para una mayor calidad. Gesti\u00f3n integradora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/\" \/>\n<meta property=\"og:site_name\" content=\"Red Educativa Fasta\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rededucativafasta\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-09T11:41:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/reunion-equipo-dgre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/noticias\\\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\\\/\",\"url\":\"https:\\\/\\\/redfasta.edu.ar\\\/noticias\\\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\\\/\",\"name\":\"Primera reuni\u00f3n del equipo actualizado de la Direcci\u00f3n General de la Red\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/noticias\\\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/noticias\\\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/redfasta.edu.ar\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/reunion-equipo-dgre.jpg\",\"datePublished\":\"2025-06-05T15:35:23+00:00\",\"dateModified\":\"2025-06-09T11:41:50+00:00\",\"description\":\"Equipo actualizado de la Direcci\u00f3n General de la Red Educativa Fasta se re\u00fane. Mayor especificidad para una mayor calidad. Gesti\u00f3n integradora\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/noticias\\\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/redfasta.edu.ar\\\/noticias\\\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/noticias\\\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\\\/#primaryimage\",\"url\":\"https:\\\/\\\/redfasta.edu.ar\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/reunion-equipo-dgre.jpg\",\"contentUrl\":\"https:\\\/\\\/redfasta.edu.ar\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/reunion-equipo-dgre.jpg\",\"width\":1400,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/noticias\\\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/redfasta.edu.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/redfasta.edu.ar\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Primera reuni\u00f3n del equipo actualizado de la Direcci\u00f3n General de la Red\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/#website\",\"url\":\"https:\\\/\\\/redfasta.edu.ar\\\/\",\"name\":\"Red Educativa Fasta\",\"description\":\"Educamos en la Verdad y el Bien\",\"publisher\":{\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/redfasta.edu.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/#organization\",\"name\":\"Red Educativa Fasta\",\"url\":\"https:\\\/\\\/redfasta.edu.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/redfasta.edu.ar\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo-header-bordo.png\",\"contentUrl\":\"https:\\\/\\\/redfasta.edu.ar\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/logo-header-bordo.png\",\"width\":200,\"height\":40,\"caption\":\"Red Educativa Fasta\"},\"image\":{\"@id\":\"https:\\\/\\\/redfasta.edu.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rededucativafasta\",\"https:\\\/\\\/www.instagram.com\\\/rededucativafasta\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/RedEducativaFasta\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Primera reuni\u00f3n del equipo actualizado de la Direcci\u00f3n General de la Red","description":"Equipo actualizado de la Direcci\u00f3n General de la Red Educativa Fasta se re\u00fane. Mayor especificidad para una mayor calidad. Gesti\u00f3n integradora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/","og_locale":"fr_FR","og_type":"article","og_title":"Primera reuni\u00f3n del equipo actualizado de la Direcci\u00f3n General de la Red","og_description":"Equipo actualizado de la Direcci\u00f3n General de la Red Educativa Fasta se re\u00fane. Mayor especificidad para una mayor calidad. Gesti\u00f3n integradora","og_url":"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/","og_site_name":"Red Educativa Fasta","article_publisher":"https:\/\/www.facebook.com\/rededucativafasta","article_modified_time":"2025-06-09T11:41:50+00:00","og_image":[{"width":1400,"height":500,"url":"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/reunion-equipo-dgre.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/","url":"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/","name":"Primera reuni\u00f3n del equipo actualizado de la Direcci\u00f3n General de la Red","isPartOf":{"@id":"https:\/\/redfasta.edu.ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/#primaryimage"},"image":{"@id":"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/#primaryimage"},"thumbnailUrl":"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/reunion-equipo-dgre.jpg","datePublished":"2025-06-05T15:35:23+00:00","dateModified":"2025-06-09T11:41:50+00:00","description":"Equipo actualizado de la Direcci\u00f3n General de la Red Educativa Fasta se re\u00fane. Mayor especificidad para una mayor calidad. Gesti\u00f3n integradora","breadcrumb":{"@id":"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/#primaryimage","url":"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/reunion-equipo-dgre.jpg","contentUrl":"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2025\/06\/reunion-equipo-dgre.jpg","width":1400,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/redfasta.edu.ar\/noticias\/primera-reunion-del-equipo-actualizado-de-la-direccion-general-de-la-red\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/redfasta.edu.ar\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/redfasta.edu.ar\/noticias\/"},{"@type":"ListItem","position":3,"name":"Primera reuni\u00f3n del equipo actualizado de la Direcci\u00f3n General de la Red"}]},{"@type":"WebSite","@id":"https:\/\/redfasta.edu.ar\/#website","url":"https:\/\/redfasta.edu.ar\/","name":"Red Educativa Fasta","description":"Educamos en la Verdad y el Bien","publisher":{"@id":"https:\/\/redfasta.edu.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/redfasta.edu.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/redfasta.edu.ar\/#organization","name":"Red Educativa Fasta","url":"https:\/\/redfasta.edu.ar\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/redfasta.edu.ar\/#\/schema\/logo\/image\/","url":"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2021\/10\/logo-header-bordo.png","contentUrl":"https:\/\/redfasta.edu.ar\/wp-content\/uploads\/2021\/10\/logo-header-bordo.png","width":200,"height":40,"caption":"Red Educativa Fasta"},"image":{"@id":"https:\/\/redfasta.edu.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rededucativafasta","https:\/\/www.instagram.com\/rededucativafasta\/","https:\/\/www.youtube.com\/c\/RedEducativaFasta"]}]}},"_links":{"self":[{"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/noticias\/373373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":7,"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/noticias\/373373\/revisions"}],"predecessor-version":[{"id":373393,"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/noticias\/373373\/revisions\/373393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/media\/373377"}],"wp:attachment":[{"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/media?parent=373373"}],"wp:term":[{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/tipo?post=373373"},{"taxonomy":"categoria","embeddable":true,"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/categoria?post=373373"},{"taxonomy":"fuente","embeddable":true,"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/fuente?post=373373"},{"taxonomy":"origen","embeddable":true,"href":"https:\/\/redfasta.edu.ar\/fr\/wp-json\/wp\/v2\/origen?post=373373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}